{"id":26940,"date":"2023-12-21T16:44:28","date_gmt":"2023-12-21T08:44:28","guid":{"rendered":"https:\/\/www.cejia.com\/portfolio\/mockup-device-mobile-app-iphone13solid-deeporange\/"},"modified":"2023-12-22T11:20:31","modified_gmt":"2023-12-22T03:20:31","slug":"mockup-device-mobile-app-iphone13solid-deeporange","status":"publish","type":"keydesign-portfolio","link":"https:\/\/www.cejia.com\/fr\/portfolio\/mockup-device-mobile-app-iphone13solid-deeporange\/","title":{"rendered":"Mat\u00e9riau orange fonc\u00e9 de couleur unie pour iPhone 13"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"26940\" class=\"elementor elementor-26940\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dadb518 e-flex e-con-boxed e-con e-parent\" data-id=\"dadb518\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d3a594e e-con-full e-flex e-con e-child\" data-id=\"d3a594e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1921722 e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"1921722\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-284a7dc animated-fast elementor-invisible elementor-widget elementor-widget-image\" data-id=\"284a7dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"IPhone 13 \u7eaf\u8272 \u6df1\u6a59\u7d20\u6750\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY5MzIsInVybCI6Imh0dHBzOlwvXC93d3cuY2VqaWEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMlwvYXBwLWlwaG9uZTEzc29saWQtZGVlcG9yYW5nZS5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1570\" height=\"2932\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange.png\" class=\"attachment-full size-full wp-image-26932\" alt=\"Mat\u00e9riau orange fonc\u00e9 de couleur unie pour iPhone 13\" srcset=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange.png 1570w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-161x300.png 161w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-548x1024.png 548w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-768x1434.png 768w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-822x1536.png 822w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-1097x2048.png 1097w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-710x1326.png 710w\" sizes=\"(max-width: 1570px) 100vw, 1570px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d55203c e-con-full animated-fast e-flex elementor-invisible e-con e-child\" data-id=\"d55203c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61c0473 animated-fast elementor-invisible elementor-widget elementor-widget-image\" data-id=\"61c0473\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-1.png\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"IPhone 13 \u7eaf\u8272 \u6df1\u6a59\u7d20\u6750|\u6a21\u677f|\u56fe\u7247|\u5916\u6846|\u6d77\u62a5|\u6837\u673a|\u5206\u8fa8\u7387|PPT|PSD|PNG|\u514d\u62a0\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjY5MzksInVybCI6Imh0dHBzOlwvXC93d3cuY2VqaWEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMlwvYXBwLWlwaG9uZTEzc29saWQtZGVlcG9yYW5nZS0xLnBuZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-1.png\" class=\"attachment-full size-full wp-image-26939\" alt=\"Mat\u00e9riau orange fonc\u00e9 de couleur unie pour iPhone 13 | mod\u00e8le | image | cadre | affiche | maquette | r\u00e9solution | PPT | PSD | PNG | d\u00e9coupe gratuite\" srcset=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-1.png 200w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange-1-150x150.png 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edd12a3 e-con-full sticky-container e-flex e-con e-child\" data-id=\"edd12a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbd9701 elementor-widget elementor-widget-elementskit-heading\" data-id=\"cbd9701\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Mat\u00e9riau orange fonc\u00e9 de couleur unie pour iPhone 13<\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Moxiu vous fournit du mat\u00e9riel de couleur unie orange fonc\u00e9 pour iPhone 13. Les param\u00e8tres de la couleur unie orange fonc\u00e9 de l&#039;iPhone 13 sont les suivants. Vous pouvez utiliser ce mat\u00e9riel directement dans Moxiu pour la conception de captures d&#039;\u00e9cran, ou vous pouvez t\u00e9l\u00e9charger ce mat\u00e9riel pour vos autres travaux.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b6b703 e-con-full e-flex e-con e-child\" data-id=\"3b6b703\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fced1a1 e-flex e-con-boxed e-con e-child\" data-id=\"fced1a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e3aa464 e-con-full e-flex e-con e-child\" data-id=\"e3aa464\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15c9c41 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"15c9c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">\u00e9quipement<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1eeac3d e-con-full e-flex e-con e-child\" data-id=\"1eeac3d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea80a3c animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"ea80a3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>t\u00e9l\u00e9phone portable<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed75123 e-flex e-con-boxed e-con e-child\" data-id=\"ed75123\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fc53f5f e-con-full e-flex e-con e-child\" data-id=\"fc53f5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cdbc47 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"2cdbc47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">syst\u00e8me op\u00e9rateur<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-69d5bd7 e-con-full e-flex e-con e-child\" data-id=\"69d5bd7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0af0469 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"0af0469\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>IOS<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4af7e45 e-flex e-con-boxed e-con e-child\" data-id=\"4af7e45\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5d9e7a3 e-con-full e-flex e-con e-child\" data-id=\"5d9e7a3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-524bfe8 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"524bfe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">groupe de p\u00e9riph\u00e9riques<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77d8bcf e-con-full e-flex e-con e-child\" data-id=\"77d8bcf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-02a8b84 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"02a8b84\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>IPhone 13 \/ IPhone 13 couleur unie<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14e4beb e-con-full e-flex e-con e-child\" data-id=\"14e4beb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1157584 e-flex e-con-boxed e-con e-child\" data-id=\"1157584\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-17f86e2 e-con-full e-flex e-con e-child\" data-id=\"17f86e2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7022d8e animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"7022d8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">couleur<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-871137c e-con-full e-flex e-con e-child\" data-id=\"871137c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c594486 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"c594486\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>orange fonc\u00e9<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49420c1 e-flex e-con-boxed e-con e-child\" data-id=\"49420c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-22dd4f5 e-con-full e-flex e-con e-child\" data-id=\"22dd4f5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-811c63d animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"811c63d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">Taille de l&#039;image (px)<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-004e3b4 e-con-full e-flex e-con e-child\" data-id=\"004e3b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3f402c animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"e3f402c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>1570 x 2932<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75044d2 e-flex e-con-boxed e-con e-child\" data-id=\"75044d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-76ad71c e-con-full e-flex e-con e-child\" data-id=\"76ad71c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1021ea2 animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"1021ea2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">Taille de l&#039;\u00e9cran interne (px)<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0ffe1ed e-con-full e-flex e-con e-child\" data-id=\"0ffe1ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-faab9fc animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"faab9fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>1180 x 2554\u00a0<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4654782 elementor-align-center elementor-widget elementor-widget-elementskit-button\" data-id=\"4654782\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/app-iphone13solid-deeporange.zip\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-arrow-alt-circle-down\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm-32-316v116h-67c-10.7 0-16 12.9-8.5 20.5l99 99c4.7 4.7 12.3 4.7 17 0l99-99c7.6-7.6 2.2-20.5-8.5-20.5h-67V140c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12z\"><\/path><\/svg>T\u00e9l\u00e9chargement de mat\u00e9riel\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-864fffe e-flex e-con-boxed e-con e-child\" data-id=\"864fffe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44ce6d8 e-con-full e-flex e-con e-child\" data-id=\"44ce6d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0eb5ae animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"b0eb5ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;css&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"ekit-heading--title elementskit-section-title\">partager<\/h6><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60a6312 e-con-full e-flex e-con e-child\" data-id=\"60a6312\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-840ceca animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-social-media\" data-id=\"840ceca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInUp&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-social-media.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t\t <ul class=\"ekit_social_media\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-172011e\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Facebook\" class=\"f\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook-f\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"><\/path><\/svg>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-0825b5a\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Twitter\" class=\"twitter\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fasicon icon-twitter\"><\/i>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-fa40825\">\n\t\t\t\t\t    <a\n\t\t\t\t\t\thref=\"#\" aria-label=\"Instagram\" class=\"instagram\" >\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\n                                                                                                            <\/a>\n                    <\/li>\n                    \t\t\t\t\t\t\t<\/ul>\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9df1734 hero-section e-flex e-con-boxed e-con e-parent\" data-id=\"9df1734\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f21d1a1 e-con-full e-flex e-con e-child\" data-id=\"f21d1a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f8b4412 e-con-full e-flex e-con e-child\" data-id=\"f8b4412\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a7f862 animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"1a7f862\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tAffichage du projet Mocshow\n\t\t\t\t\t<\/h6><h1 class=\"ekit-heading--title elementskit-section-title\">Affichage du projet de capture d&#039;\u00e9cran orange fonc\u00e9 de couleur unie de l&#039;iPhone 13<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Ce cas montre comment Moxiu a utilis\u00e9 le mat\u00e9riau orange fonc\u00e9 de couleur unie de l&#039;iPhone 13 pour concevoir une capture d&#039;\u00e9cran de l&#039;application pour un projet r\u00e9el. Ce projet comprend 5 captures d&#039;\u00e9cran avec la coque.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6250d68 elementor-icon-list--layout-inline elementor-tablet-align-center elementor-widget__width-initial elementor-align-center animated-fast elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"6250d68\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Convient aux magasins d&#039;applications mobiles, de bureau et autres<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le mat\u00e9riel de t\u00e9l\u00e9phone portable orange fonc\u00e9 de couleur unie iPhone 13 le plus r\u00e9cent et le plus tendance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">R\u00e9ussissez facilement l&#039;examen de l&#039;App Store<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cfec0a5 e-con-full e-flex e-con e-child\" data-id=\"cfec0a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9d41566 e-con-full e-flex e-con e-child\" data-id=\"9d41566\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-dd3a551 e-con-full e-flex e-con e-child\" data-id=\"dd3a551\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-294008d animated-fast elementor-pagination-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"294008d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/page-bcbd-8f69.jpeg\" alt=\"Mod\u00e8le orange fonc\u00e9 de couleur unie pour iPhone 13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/page-0e8f-3055.jpeg\" alt=\"Image orange fonc\u00e9 de couleur unie pour iPhone 13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/page-57bd-3a5b.jpeg\" alt=\"Cadre orange fonc\u00e9 de couleur unie pour iPhone 13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/page-7fc6-e640.jpeg\" alt=\"Affiche orange fonc\u00e9 de couleur unie pour iPhone 13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\" data-no-translation-aria-label=\"\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/12\/page-8cb2-01bc.jpeg\" alt=\"Maquette orange fonc\u00e9 de couleur unie pour iPhone 13\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6599bbc e-flex e-con-boxed e-con e-parent\" data-id=\"6599bbc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-20efc9f e-con-full e-flex e-con e-child\" data-id=\"20efc9f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8b025d9 e-con-full e-flex e-con e-child\" data-id=\"8b025d9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-530169f animated-fast elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-elementskit-heading\" data-id=\"530169f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:100,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h6 class=\"elementskit-section-subtitle  elementskit-style-border\">\n\t\t\t\t\t\tCaract\u00e9ristiques fonctionnelles\n\t\t\t\t\t<\/h6><h1 class=\"ekit-heading--title elementskit-section-title\"><span>mocshow<\/span> Am\u00e9liorer la vie des d\u00e9veloppeurs<\/h1>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Nous avons cr\u00e9\u00e9 un excellent produit avec des innovations massives dans la conception de logiciels et de captures d&#039;\u00e9cran d&#039;applications. La ma\u00eetrise de la fonction mocshow vous permet de cr\u00e9er de meilleurs produits en un temps plus court.<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db694e0 elementor-align-left elementor-widget__width-auto animated-fast elementor-invisible elementor-widget elementor-widget-elementskit-button\" data-id=\"db694e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;pulse&quot;,&quot;_animation_delay&quot;:200,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-button.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-btn-wraper\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.cejia.com\/fr\/telecharger\/\" class=\"elementskit-btn  whitespace--normal\" id=\"\">\n\t\t\t\t\tT\u00e9l\u00e9chargez maintenant pour exp\u00e9rimenter\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3113c97 elementor-icon-list--layout-inline elementor-tablet-align-center elementor-widget__width-initial animated-fast elementor-align-center elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"3113c97\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">0 basique<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Rapide 90%<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bon 90%<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/pay.weixin.qq.com\/\" target=\"_blank\" title=\"WeChat Payer pour Changer\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check-circle\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256c0 136.967-111.033 248-248 248S8 392.967 8 256 119.033 8 256 8s248 111.033 248 248zM227.314 387.314l184-184c6.248-6.248 6.248-16.379 0-22.627l-22.627-22.627c-6.248-6.249-16.379-6.249-22.628 0L216 308.118l-70.059-70.059c-6.248-6.248-16.379-6.248-22.628 0l-22.627 22.627c-6.248 6.248-6.248 16.379 0 22.627l104 104c6.249 6.249 16.379 6.249 22.628.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Comment?<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-80c3a6d e-con-full e-flex e-con e-child\" data-id=\"80c3a6d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-953ae64 e-con-full e-flex e-con e-child\" data-id=\"953ae64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-215bc26 widget-link-underline animated-fast ekit-equal-height-enable elementor-invisible elementor-widget elementor-widget-elementskit-image-box\" data-id=\"215bc26\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-center hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-center\">\n\n                    <img decoding=\"async\" width=\"768\" height=\"577\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/09\/6b686cd5-5bac-4688-ab91-24f47392fa28-768x577.webp\" class=\"attachment-medium_large size-medium_large wp-image-23398\" alt=\"Fonction Mocshow\" srcset=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/09\/6b686cd5-5bac-4688-ab91-24f47392fa28-768x577.webp 768w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/09\/6b686cd5-5bac-4688-ab91-24f47392fa28-300x226.webp 300w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/09\/6b686cd5-5bac-4688-ab91-24f47392fa28-1024x770.webp 1024w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/09\/6b686cd5-5bac-4688-ab91-24f47392fa28-710x534.webp 710w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/09\/6b686cd5-5bac-4688-ab91-24f47392fa28.webp 1152w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        haute efficacit\u00e9\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Avec une seule conception, vous pouvez produire des captures d&#039;\u00e9cran conformes qui r\u00e9pondent aux exigences de plus de 10 centres d&#039;applications. Il prend \u00e9galement en charge l&#039;internationalisation des produits et l&#039;utilisation de plusieurs appareils. Le projet modulaire acc\u00e9l\u00e8re la mise \u00e0 jour et la maintenance des applications.                    <\/div>\n                                    <\/div>\n\n                                <div class=\"elementskit-box-footer\">\n                    <div class=\"box-footer\">\n                        <div class=\"btn-wraper\">\n                                                            <a href=\"#section1\" class=\"elementskit-btn whitespace--normal\">\n                                    Structure de projet modulaire                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14d9194 e-con-full e-flex e-con e-child\" data-id=\"14d9194\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6149b6a widget-link-underline animated-fast ekit-equal-height-enable elementor-invisible elementor-widget elementor-widget-elementskit-image-box\" data-id=\"6149b6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-center hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-center\">\n\n                    <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"577\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/big-power-768x577.jpg\" class=\"attachment-medium_large size-medium_large wp-image-23442\" alt=\"\u4e0a\u67b6\u4e2d\u56fd\" srcset=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/big-power-768x577.jpg 768w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/big-power-300x226.jpg 300w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/big-power-1024x770.jpg 1024w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/big-power-710x534.jpg 710w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/big-power.jpg 1152w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Base z\u00e9ro\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Aucune exp\u00e9rience en dessin n&#039;est requise. Tout novice peut g\u00e9n\u00e9rer plus de 99% captures d&#039;\u00e9cran d&#039;applications r\u00e9pertori\u00e9es sur le march\u00e9 des applications en 1% de l&#039;\u00e9poque d&#039;un concepteur traditionnel. Il n&#039;est pas n\u00e9cessaire de demander de l&#039;aide pour faire des captures d&#039;\u00e9cran pour les listes d&#039;applications logicielles.                    <\/div>\n                                    <\/div>\n\n                                <div class=\"elementskit-box-footer\">\n                    <div class=\"box-footer\">\n                        <div class=\"btn-wraper\">\n                                                            <a href=\"#section2\" class=\"elementskit-btn whitespace--normal\">\n                                    Caract\u00e9ristiques de conception simples                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-92d2bdc e-con-full e-flex e-con e-child\" data-id=\"92d2bdc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7251d90 widget-link-underline animated-fast ekit-equal-height-enable elementor-invisible elementor-widget elementor-widget-elementskit-image-box\" data-id=\"7251d90\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:200,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-center hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-center\">\n\n                    <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"577\" src=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/home-office-768x577.jpg\" class=\"attachment-medium_large size-medium_large wp-image-23443\" alt=\"Bureau de Mo Xiuyun\" srcset=\"https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/home-office-768x577.jpg 768w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/home-office-300x226.jpg 300w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/home-office-1024x770.jpg 1024w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/home-office-710x534.jpg 710w, https:\/\/www.cejia.com\/wp-content\/uploads\/2023\/11\/home-office.jpg 1152w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        faibles exigences\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Aucune machine performante n&#039;est requise, juste un t\u00e9l\u00e9phone portable et vous pouvez commencer \u00e0 travailler \u00e0 tout moment et n&#039;importe o\u00f9. Que ce soit au bureau, \u00e0 la salle de sport ou sous les couvertures, vous pouvez effectuer un travail de haute qualit\u00e9.                    <\/div>\n                                    <\/div>\n\n                                <div class=\"elementskit-box-footer\">\n                    <div class=\"box-footer\">\n                        <div class=\"btn-wraper\">\n                                                            <a href=\"https:\/\/www.cejia.com\/fr\/telecharger\/\" class=\"elementskit-btn whitespace--normal\">\n                                    Prise en charge client compl\u00e8te de la plateforme                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4a1cd1 e-flex e-con-boxed e-con e-parent\" data-id=\"d4a1cd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70d10ff elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"70d10ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Moxiu fournit une multitude de mat\u00e9riaux, notamment un mod\u00e8le orange fonc\u00e9 de couleur unie pour iPhone 13, une image orange fonc\u00e9 de couleur unie pour iPhone 13, un cadre orange fonc\u00e9 de couleur unie pour iPhone 13, une affiche orange fonc\u00e9 de couleur unie pour iPhone 13, une maquette orange fonc\u00e9 de couleur unie pour iPhone 13, un iPhone R\u00e9solution orange fonc\u00e9 de 13 couleurs unies, PPT de couleur unie orange fonc\u00e9 pour iPhone 13, PSD orange fonc\u00e9 pour iPhone 13 de couleur unie, PNG orange fonc\u00e9 de couleur unie pour iPhone 13, orange fonc\u00e9 de couleur unie pour iPhone 13 sans d\u00e9coupe<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>mod\u00e8le<\/p>","protected":false},"author":1,"featured_media":26939,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_elementor_version":"3.17.3","footnotes":""},"portfolioCat":[1940],"class_list":["post-26940","keydesign-portfolio","type-keydesign-portfolio","status-publish","has-post-thumbnail","hentry","keydesign-portfolio-category-mockup-device-mobile-ios-iphone13"],"_links":{"self":[{"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/portfolio\/26940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/types\/keydesign-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/comments?post=26940"}],"version-history":[{"count":0,"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/portfolio\/26940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/media\/26939"}],"wp:attachment":[{"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/media?parent=26940"}],"wp:term":[{"taxonomy":"keydesign-portfolio-category","embeddable":true,"href":"https:\/\/www.cejia.com\/fr\/wp-json\/wp\/v2\/portfolioCat?post=26940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}